{"id":1477,"date":"2024-10-06T08:41:33","date_gmt":"2024-10-06T08:41:33","guid":{"rendered":"https:\/\/charcoals.ae\/iletisim\/"},"modified":"2024-11-05T12:56:44","modified_gmt":"2024-11-05T12:56:44","slug":"iletisim","status":"publish","type":"page","link":"https:\/\/charcoals.ae\/tr\/iletisim\/","title":{"rendered":"\u0130leti\u015fim"},"content":{"rendered":"\n<div class=\"wp-block-greenshift-blocks-row alignfull gspb_row gspb_row-id-gsbp-df20712\" id=\"gspb_row-id-gsbp-df20712\"><div class=\"gspb_backgroundOverlay\"><\/div><div class=\"gspb_row__content\"> \n<div class=\"wp-block-greenshift-blocks-row-column gspb_row__col--12 gspb_col-id-gsbp-5341515\" id=\"gspb_col-id-gsbp-5341515\">\n\n\n<h2 id=\"gspb_heading-id-gsbp-76e138e\" class=\"gspb_heading gspb_heading-id-gsbp-76e138e \"><strong>Sipari\u015f Vermeye Haz\u0131r M\u0131s\u0131n\u0131z?<\/strong> <\/h2>\n\n\n\n<p id=\"gspb_text-id-gsbp-72ef05c\" class=\"gspb_text gspb_text-id-gsbp-72ef05c \">Bizi aray\u0131n veya formu doldurun! Sat\u0131n alma s\u00fcrecinde size rehberlik edelim. <\/p>\n<\/div>\n <\/div><\/div>\n\n<div class=\"wp-block-greenshift-blocks-row gspb_row gspb_row-id-gsbp-fbdca79\" id=\"gspb_row-id-gsbp-fbdca79\"><div class=\"gspb_row__content\"> \n<div class=\"wp-block-greenshift-blocks-row-column gspb_row__col--6 gspb_row__col--md-12 gspb_col-id-gsbp-f2c161c\" id=\"gspb_col-id-gsbp-f2c161c\"><div class=\"gspb_backgroundOverlay\"><\/div>\n<div class=\"wp-block-greenshift-blocks-row gspb_row gspb_row-id-gsbp-7313fdb\" id=\"gspb_row-id-gsbp-7313fdb\"><div class=\"gspb_row__content\"> \n<div class=\"wp-block-greenshift-blocks-row-column gspb_row__col--6 gspb_col-id-gsbp-272c810\" id=\"gspb_col-id-gsbp-272c810\">\n<div class=\"wp-block-greenshift-blocks-image gspb_image gspb_image-id-gsbp-2bfe568\" id=\"gspb_image-id-gsbp-2bfe568\"><img decoding=\"async\" src=\"https:\/\/charcoals.ae\/wp-content\/uploads\/2024\/10\/Map-2.svg\" data-src=\"\" alt=\"\" loading=\"lazy\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-greenshift-blocks-row-column gspb_row__col--6 gspb_col-id-gsbp-2047624\" id=\"gspb_col-id-gsbp-2047624\">\n<h3 id=\"gspb_heading-id-gsbp-29e9c67\" class=\"gspb_heading gspb_heading-id-gsbp-29e9c67 \">Adres<\/h3>\n\n\n\n<div id=\"gspb_text-id-gsbp-692c534\" class=\"gspb_text gspb_text-id-gsbp-692c534 \">Unit 402, Fourth Floor, Doha center, Al-maktoum Rd, Deira, Dubai, UAE<\/div>\n<\/div>\n <\/div><\/div>\n\n\n\n<div class=\"wp-block-greenshift-blocks-row gspb_row gspb_row-id-gsbp-f34f773\" id=\"gspb_row-id-gsbp-f34f773\"><div class=\"gspb_row__content\"> \n<div class=\"wp-block-greenshift-blocks-row-column gspb_row__col--6 gspb_col-id-gsbp-aa0d36a\" id=\"gspb_col-id-gsbp-aa0d36a\">\n<div class=\"wp-block-greenshift-blocks-image gspb_image gspb_image-id-gsbp-a27dbf3\" id=\"gspb_image-id-gsbp-a27dbf3\"><img decoding=\"async\" src=\"https:\/\/charcoals.ae\/wp-content\/uploads\/2024\/10\/Phone.svg\" data-src=\"\" alt=\"\" loading=\"lazy\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-greenshift-blocks-row-column gspb_row__col--6 gspb_col-id-gsbp-78de9ff\" id=\"gspb_col-id-gsbp-78de9ff\">\n<h3 id=\"gspb_heading-id-gsbp-632c3e5\" class=\"gspb_heading gspb_heading-id-gsbp-632c3e5 \">Telefon Numaras\u0131<\/h3>\n\n\n\n<div id=\"gspb_text-id-gsbp-5446d73\" class=\"gspb_text gspb_text-id-gsbp-5446d73 \">(+971)-50-8846424<\/div>\n\n\n\n<div id=\"gspb_text-id-gsbp-d900805\" class=\"gspb_text gspb_text-id-gsbp-d900805 \">(+971)-50-8812441<\/div>\n<\/div>\n <\/div><\/div>\n\n\n\n<div class=\"wp-block-greenshift-blocks-row gspb_row gspb_row-id-gsbp-cc0f9d0\" id=\"gspb_row-id-gsbp-cc0f9d0\"><div class=\"gspb_row__content\"> \n<div class=\"wp-block-greenshift-blocks-row-column gspb_row__col--6 gspb_col-id-gsbp-928acbf\" id=\"gspb_col-id-gsbp-928acbf\">\n<div class=\"wp-block-greenshift-blocks-image gspb_image gspb_image-id-gsbp-e1a6522\" id=\"gspb_image-id-gsbp-e1a6522\"><img decoding=\"async\" src=\"https:\/\/charcoals.ae\/wp-content\/uploads\/2024\/10\/Email.svg\" data-src=\"\" alt=\"\" loading=\"lazy\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-greenshift-blocks-row-column gspb_row__col--6 gspb_col-id-gsbp-83bb57e\" id=\"gspb_col-id-gsbp-83bb57e\">\n<h3 id=\"gspb_heading-id-gsbp-9d40c38\" class=\"gspb_heading gspb_heading-id-gsbp-9d40c38 \">E-posta Adresi<\/h3>\n\n\n\n<div id=\"gspb_text-id-gsbp-a61e76b\" class=\"gspb_text gspb_text-id-gsbp-a61e76b \"><a href=\"mailto:sales@charcoals.ae\">Sales@charcoals.ae<\/a><br\/><a href=\"mailto:commercial@charcoals.ae\">Commercial@charcoals.ae<\/a><\/div>\n<\/div>\n <\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-greenshift-blocks-row-column gspb_row__col--6 gspb_row__col--md-12 gspb_col-id-gsbp-048e4e0\" id=\"gspb_col-id-gsbp-048e4e0\">\n<h3 id=\"gspb_heading-id-gsbp-8f74937\" class=\"gspb_heading gspb_heading-id-gsbp-8f74937 \">Bizimle ileti\u015fime ge\u00e7in<\/h3>\n\n\n\n<div id=\"gspb_text-id-gsbp-6106b59\" class=\"gspb_text gspb_text-id-gsbp-6106b59 \">A\u015fa\u011f\u0131daki formu doldurun, en k\u0131sa s\u00fcrede size geri d\u00f6n\u00fc\u015f yapaca\u011f\u0131z.<\/div>\n\n\n<style>.wp-block-kadence-advanced-form669-cpt-id .kb-advanced-form input[type=text],.wp-block-kadence-advanced-form669-cpt-id .kb-advanced-form input[type=tel],.wp-block-kadence-advanced-form669-cpt-id .kb-advanced-form input[type=number],.wp-block-kadence-advanced-form669-cpt-id .kb-advanced-form input[type=date],.wp-block-kadence-advanced-form669-cpt-id .kb-advanced-form input[type=time],.wp-block-kadence-advanced-form669-cpt-id .kb-advanced-form input[type=email],.wp-block-kadence-advanced-form669-cpt-id .kb-advanced-form input[type=file],.wp-block-kadence-advanced-form669-cpt-id .kb-advanced-form select,.wp-block-kadence-advanced-form669-cpt-id .kb-advanced-form textarea{color:var(--theme-palette-color-4, #2C1E18);border-top:1px solid transparent;border-right:1px solid transparent;border-bottom:1px solid transparent;border-left:1px solid transparent;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.wp-block-kadence-advanced-form669-cpt-id{--kb-form-text-color:var(--theme-palette-color-4, #2C1E18);--kb-form-background-color:rgba(255,255,255,0.16);--kb-form-border-width:1px;}.wp-block-kadence-advanced-form669-cpt-id{--kb-form-placeholder-color:rgba(246,246,246,0.44);}.wp-block-kadence-advanced-form669-cpt-id input[type=text]:focus,.wp-block-kadence-advanced-form669-cpt-id input[type=email]:focus,.wp-block-kadence-advanced-form669-cpt-id input[type=tel]:focus,.wp-block-kadence-advanced-form669-cpt-id input[type=date]:focus,.wp-block-kadence-advanced-form669-cpt-id input[type=number]:focus,.wp-block-kadence-advanced-form669-cpt-id input[type=time]:focus,.wp-block-kadence-advanced-form669-cpt-id input[type=file]:focus,.wp-block-kadence-advanced-form669-cpt-id select:focus,.wp-block-kadence-advanced-form669-cpt-id textarea:focus{color:var(--theme-palette-color-8, #ffffff);}.wp-block-kadence-advanced-form669-cpt-id .kb-adv-form-field .kb-adv-form-label{font-family:ct_font_poppins;color:var(--theme-palette-color-4, #2C1E18);}@media all and (max-width: 1024px){.wp-block-kadence-advanced-form669-cpt-id .kb-advanced-form input[type=text],.wp-block-kadence-advanced-form669-cpt-id .kb-advanced-form input[type=tel],.wp-block-kadence-advanced-form669-cpt-id .kb-advanced-form input[type=number],.wp-block-kadence-advanced-form669-cpt-id .kb-advanced-form input[type=date],.wp-block-kadence-advanced-form669-cpt-id .kb-advanced-form input[type=time],.wp-block-kadence-advanced-form669-cpt-id .kb-advanced-form input[type=email],.wp-block-kadence-advanced-form669-cpt-id .kb-advanced-form input[type=file],.wp-block-kadence-advanced-form669-cpt-id .kb-advanced-form select,.wp-block-kadence-advanced-form669-cpt-id .kb-advanced-form textarea{border-top:1px solid transparent;border-right:1px solid transparent;border-bottom:1px solid transparent;border-left:1px solid transparent;}}@media all and (max-width: 767px){.wp-block-kadence-advanced-form669-cpt-id .kb-advanced-form input[type=text],.wp-block-kadence-advanced-form669-cpt-id .kb-advanced-form input[type=tel],.wp-block-kadence-advanced-form669-cpt-id .kb-advanced-form input[type=number],.wp-block-kadence-advanced-form669-cpt-id .kb-advanced-form input[type=date],.wp-block-kadence-advanced-form669-cpt-id .kb-advanced-form input[type=time],.wp-block-kadence-advanced-form669-cpt-id .kb-advanced-form input[type=email],.wp-block-kadence-advanced-form669-cpt-id .kb-advanced-form input[type=file],.wp-block-kadence-advanced-form669-cpt-id .kb-advanced-form select,.wp-block-kadence-advanced-form669-cpt-id .kb-advanced-form textarea{border-top:1px solid transparent;border-right:1px solid transparent;border-bottom:1px solid transparent;border-left:1px solid transparent;}}<\/style><div class=\"wp-block-kadence-advanced-form wp-block-kadence-advanced-form669-cpt-id kb-adv-form-label-style-normal kb-adv-form-input-size-standard kb-form-basic-style wp-block-kadence-advanced-form\"><form id=\"kb-adv-form-669-cpt-id\" class=\"kb-advanced-form\" method=\"post\">\n<style>.kb-row-layout-id669_b11366-ed > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id669_b11366-ed > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id669_b11366-ed > .kt-row-column-wrap{column-gap:10px;row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id669_b11366-ed > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id669_b11366-ed > .kt-row-column-wrap{column-gap:10px;grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id669_b11366-ed > .kt-row-column-wrap{column-gap:10px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id669_b11366-ed alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column669_1f6167-68 > .kt-inside-inner-col,.kadence-column669_1f6167-68 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column669_1f6167-68 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column669_1f6167-68 > .kt-inside-inner-col{flex-direction:column;}.kadence-column669_1f6167-68 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column669_1f6167-68 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column669_1f6167-68{position:relative;}@media all and (max-width: 1024px){.kadence-column669_1f6167-68 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column669_1f6167-68 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column669_1f6167-68\"><div class=\"kt-inside-inner-col\"><div class=\"kb-adv-form-field kb-adv-form-text-type-input kb-adv-form-infield-type-input kb-field6691f9c07-0a wp-block-kadence-advanced-form-text\"><label class=\"kb-adv-form-label\" for=\"field6691f9c07-0a\">Name<span class=\"kb-adv-form-required\">*<\/span><\/label><input name=\"field1f9c07-0a\" id=\"field6691f9c07-0a\" data-label=\"Name\" type=\"text\" placeholder=\"\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-field\" data-required=\"yes\" required aria-required=\"true\"\/><\/div><\/div><\/div>\n\n\n<style>.kadence-column669_750b17-83 > .kt-inside-inner-col,.kadence-column669_750b17-83 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column669_750b17-83 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column669_750b17-83 > .kt-inside-inner-col{flex-direction:column;}.kadence-column669_750b17-83 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column669_750b17-83 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column669_750b17-83{position:relative;}@media all and (max-width: 1024px){.kadence-column669_750b17-83 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column669_750b17-83 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column669_750b17-83\"><div class=\"kt-inside-inner-col\"><div class=\"kb-adv-form-field kb-adv-form-text-type-input kb-adv-form-infield-type-input kb-field6693631ef-54 wp-block-kadence-advanced-form-text\"><label class=\"kb-adv-form-label\" for=\"field6693631ef-54\">Family Name<span class=\"kb-adv-form-required\">*<\/span><\/label><input name=\"field3631ef-54\" id=\"field6693631ef-54\" data-label=\"Family Name\" type=\"text\" placeholder=\"\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-field\" data-required=\"yes\" required aria-required=\"true\"\/><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id669_bd180c-d7 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id669_bd180c-d7 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id669_bd180c-d7 > .kt-row-column-wrap{column-gap:10px;row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id669_bd180c-d7 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id669_bd180c-d7 > .kt-row-column-wrap{column-gap:10px;grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id669_bd180c-d7 > .kt-row-column-wrap{column-gap:10px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id669_bd180c-d7 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column669_44a113-01 > .kt-inside-inner-col,.kadence-column669_44a113-01 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column669_44a113-01 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column669_44a113-01 > .kt-inside-inner-col{flex-direction:column;}.kadence-column669_44a113-01 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column669_44a113-01 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column669_44a113-01{position:relative;}@media all and (max-width: 1024px){.kadence-column669_44a113-01 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column669_44a113-01 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column669_44a113-01\"><div class=\"kt-inside-inner-col\"><div class=\"kb-adv-form-field kb-adv-form-text-type-input kb-adv-form-infield-type-input kb-field669ec0bc3-5f wp-block-kadence-advanced-form-email\"><label class=\"kb-adv-form-label\" for=\"field669ec0bc3-5f\">Email<span class=\"kb-adv-form-required\">*<\/span><\/label><input name=\"fieldec0bc3-5f\" id=\"field669ec0bc3-5f\" data-label=\"Email\" type=\"email\" placeholder=\"\" value=\"\" data-type=\"email\" class=\"kb-field kb-email-field\" data-required=\"yes\" required aria-required=\"true\"\/><\/div><\/div><\/div>\n\n\n<style>.kadence-column669_60bcb4-25 > .kt-inside-inner-col,.kadence-column669_60bcb4-25 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column669_60bcb4-25 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column669_60bcb4-25 > .kt-inside-inner-col{flex-direction:column;}.kadence-column669_60bcb4-25 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column669_60bcb4-25 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column669_60bcb4-25{position:relative;}@media all and (max-width: 1024px){.kadence-column669_60bcb4-25 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column669_60bcb4-25 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column669_60bcb4-25\"><div class=\"kt-inside-inner-col\"><div class=\"kb-adv-form-field kb-adv-form-text-type-input kb-adv-form-infield-type-input kb-field669af986f-e4 wp-block-kadence-advanced-form-telephone\"><label class=\"kb-adv-form-label\" for=\"field669af986f-e4\">Phone Number<span class=\"kb-adv-form-required\">*<\/span><\/label><input name=\"fieldaf986f-e4\" id=\"field669af986f-e4\" data-label=\"Phone Number\" type=\"tel\" placeholder=\"\" value=\"\" data-type=\"tel\" class=\"kb-field kb-tel-field\" data-required=\"yes\" required aria-required=\"true\"\/><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id669_c9714f-86 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id669_c9714f-86 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id669_c9714f-86 > .kt-row-column-wrap{column-gap:10px;row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id669_c9714f-86 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id669_c9714f-86 > .kt-row-column-wrap{column-gap:10px;grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id669_c9714f-86 > .kt-row-column-wrap{column-gap:10px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id669_c9714f-86 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-equal kt-row-valign-top\">\n<style>.kadence-column669_72e449-26 > .kt-inside-inner-col,.kadence-column669_72e449-26 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column669_72e449-26 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column669_72e449-26 > .kt-inside-inner-col{flex-direction:column;}.kadence-column669_72e449-26 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column669_72e449-26 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column669_72e449-26{position:relative;}@media all and (max-width: 1024px){.kadence-column669_72e449-26 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column669_72e449-26 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column669_72e449-26\"><div class=\"kt-inside-inner-col\"><div class=\"kb-adv-form-field kb-adv-form-infield-type-input kb-field669b7a8d6-83 wp-block-kadence-advanced-form-select\"><label class=\"kb-adv-form-label\" for=\"field669b7a8d6-83\">Your Request for<span class=\"kb-adv-form-required\">*<\/span><\/label><select  name=\"fieldb7a8d6-83\" id=\"field669b7a8d6-83\" required aria-required=\"true\"><option value=\"Carboz Products\">Carboz Products<\/option><option value=\"OEM\">OEM<\/option><option value=\"Request for partnership\">Request for partnership<\/option><\/select><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<div class=\"kb-adv-form-field kb-adv-form-text-type-input kb-adv-form-infield-type-input kb-field6696f85c8-54 wp-block-kadence-advanced-form-textarea\"><label class=\"kb-adv-form-label\" for=\"field6696f85c8-54\">Message<span class=\"kb-adv-form-required\">*<\/span><\/label><textarea name=\"field6f85c8-54\" id=\"field6696f85c8-54\" rows=\"3\"  data-label=\"Message\" placeholder=\"\" data-type=\"textarea\" class=\"kb-field kb-textarea-field\" data-required=\"yes\" required aria-required=\"true\"><\/textarea><\/div>\n\n<style>ul.menu .kb-submit-field .kb-btn9cfdff-21.kb-button{width:initial;}.kb-submit-field .kb-btn9cfdff-21.kb-button{background:var(--theme-palette-color-1, #CB602C);font-family:Poppins;font-weight:600;}.kb-submit-field .kb-btn9cfdff-21.kb-button:hover, .kb-submit-field .kb-btn9cfdff-21.kb-button:focus{background:var(--theme-palette-color-2, #B24510);}.kb-submit-field.kb-field9cfdff-21{justify-content:flex-start;}@media all and (max-width: 767px){.kb-submit-field .kb-btn9cfdff-21.kb-button{font-size:var(--global-kb-font-size-sm, 0.9rem);}}<\/style><div class=\"kb-adv-form-field kb-submit-field kb-field9cfdff-21 wp-block-kadence-advanced-form-submit\"><button class=\"kb-button kt-button button kb-adv-form-submit-button kb-btn9cfdff-21 kt-btn-size-small kt-btn-width-type-full kb-btn-global-inherit kt-btn-has-text-true kt-btn-has-svg-false wp-block-button__link\" type=\"submit\"><span class=\"kt-btn-inner-text\">Submit<\/span><\/button><\/div>\n<input type=\"hidden\" name=\"_kb_adv_form_post_id\" value=\"669\"><input type=\"hidden\" name=\"action\" value=\"kb_process_advanced_form_submit\"><input type=\"hidden\" name=\"_kb_adv_form_id\" value=\"669-cpt-id\"><\/form><\/div><\/div>\n <\/div><\/div>\n\n<div class=\"wp-block-greenshift-blocks-row gspb_row gspb_row-id-gsbp-15caefc\" id=\"gspb_row-id-gsbp-15caefc\"><div class=\"gspb_row__content\"> \n<div class=\"wp-block-greenshift-blocks-row-column gspb_row__col--8 gspb_col-id-gsbp-63e0ec3\" id=\"gspb_col-id-gsbp-63e0ec3\">\n<h3 id=\"gspb_heading-id-gsbp-0903a06\" class=\"gspb_heading gspb_heading-id-gsbp-0903a06 \">Buraday\u0131z<\/h3>\n\n\n\n<div id=\"gspb_text-id-gsbp-c280505\" class=\"gspb_text gspb_text-id-gsbp-c280505 \">T\u00fcm ihtiya\u00e7lar\u0131n\u0131z\u0131 \u00e7evrimi\u00e7i olarak \u00e7\u00f6zmek i\u00e7in buraday\u0131z, ancak bizi \u015fahsen ziyaret etmek isterseniz, a\u015fa\u011f\u0131da adresimizi bulabilirsiniz. Kap\u0131lar\u0131m\u0131z her zaman size yard\u0131mc\u0131 olmak i\u00e7in a\u00e7\u0131kt\u0131r! <\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-greenshift-blocks-row-column gspb_row__col--4 gspb_col-id-gsbp-e0439e7\" id=\"gspb_col-id-gsbp-e0439e7\"><div class=\"gspb_id-gsbp-cce1b4c wp-block-greenshift-blocks-map\"><div data-key=\"gspb_id_gsbp_cce1b4c\" class=\"gspb_map-wrapper gspb_osmap\" id=\"gspb_map-gsbp-cce1b4c\"><\/div><\/div><\/div>\n <\/div><\/div>\n\n<div class=\"wp-block-greenshift-blocks-row alignfull gspb_row gspb_row-id-gsbp-6af23b1\" id=\"gspb_row-id-gsbp-6af23b1\"><div class=\"gspb_backgroundOverlay\"><\/div><div class=\"gspb_row__content\"> \n<div class=\"wp-block-greenshift-blocks-row-column gspb_row__col--6 gspb_row__col--md-12 gspb_row__col--xs-12 gspb_col-id-gsbp-8b2cd7c\" id=\"gspb_col-id-gsbp-8b2cd7c\">\n<h3 id=\"gspb_heading-id-gsbp-c32886f\" class=\"gspb_heading gspb_heading-id-gsbp-c32886f \">S\u0131k\u00e7a Sorulan Sorular<\/h3>\n\n\n\n<div id=\"gspb_text-id-gsbp-3a84d44\" class=\"gspb_text gspb_text-id-gsbp-3a84d44 \">\u00dcr\u00fcnlerimizle ilgili s\u0131k\u00e7a sorulan sorulara burada yan\u0131t bulabilirsiniz.<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-greenshift-blocks-row-column gspb_row__col--6 gspb_row__col--md-12 gspb_row__col--xs-12 gspb_col-id-gsbp-dd5b85c\" id=\"gspb_col-id-gsbp-dd5b85c\">\n<div class=\"wp-block-greenshift-blocks-accordion gs-accordion gspb_accordion-id-gsbp-af50371\" id=\"gspb_accordion-id-gsbp-af50371\" >\n<div class=\"wp-block-greenshift-blocks-accordionitem gs-accordion-item gspb_accordionitem-gsbp-e8bb661 gsopen\" id=\"gspb_accordionitem-gsbp-e8bb661\" itemscope><div id=\"gs-trigger-gsbp-af50371-0\" class=\"gs-accordion-item__title\" aria-expanded=\"true\" role=\"button\" tabindex=\"0\" aria-controls=\"gspb-accordion-item-content-gsbp-e8bb661\"><div class=\"gs-accordion-item__heading\"><strong>Nas\u0131l sipari\u015f verebilirim?<\/strong><\/div><meta itemprop=\"name\" content=\"<strong&gt;How can I place an order?<\/strong&gt;\"\/><span class=\"iconfortoggle\"><span class=\"gs-iconbefore\"><\/span><span class=\"gs-iconafter\"><\/span><\/span><\/div><div aria-labelledby=\"gs-trigger-gsbp-af50371-0\" class=\"gs-accordion-item__content\" itemscope id=\"gspb-accordion-item-content-gsbp-e8bb661\" aria-hidden=\"false\"><div class=\"gs-accordion-item__text\" itemprop=\"text\">\n<p class=\"has-palette-color-3-color has-text-color has-link-color wp-elements-8d5b8f9330d6eb3bc586c03d031fcddd\">Yard\u0131m almak i\u00e7in uzmanlar\u0131m\u0131z\u0131 do\u011frudan arayabilir veya web sitemizdeki sipari\u015f formunu doldurabilirsiniz. Formu g\u00f6nderdikten sonra, ekibimizden bir yetkili sizinle ileti\u015fime ge\u00e7erek detaylar\u0131 onaylayacak ve sipari\u015finizi tamamlayacakt\u0131r. <\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-greenshift-blocks-accordionitem gs-accordion-item gspb_accordionitem-gsbp-f27e73d gsclose\" id=\"gspb_accordionitem-gsbp-f27e73d\" itemscope><div id=\"gs-trigger-gsbp-af50371-1\" class=\"gs-accordion-item__title\" aria-expanded=\"false\" role=\"button\" tabindex=\"0\" aria-controls=\"gspb-accordion-item-content-gsbp-f27e73d\"><div class=\"gs-accordion-item__heading\"><strong>\u00dcr\u00fcnleriniz s\u00fcrd\u00fcr\u00fclebilir mi?<\/strong><\/div><meta itemprop=\"name\" content=\"<strong&gt;Are your products sustainable?<\/strong&gt;\"\/><span class=\"iconfortoggle\"><span class=\"gs-iconbefore\"><\/span><span class=\"gs-iconafter\"><\/span><\/span><\/div><div aria-labelledby=\"gs-trigger-gsbp-af50371-1\" class=\"gs-accordion-item__content\" itemscope id=\"gspb-accordion-item-content-gsbp-f27e73d\" aria-hidden=\"true\"><div class=\"gs-accordion-item__text\" itemprop=\"text\">\n<p class=\"has-palette-color-3-color has-text-color has-link-color wp-elements-27dbd0997b3ad9955de30599d316cc77\">Evet, s\u00fcrd\u00fcr\u00fclebilirlik misyonumuzun temel bir par\u00e7as\u0131d\u0131r. T\u00fcm \u00fcr\u00fcnlerimiz, \u00e7evresel etkiyi en aza indirmek i\u00e7in do\u011fal ve \u00e7evre dostu bile\u015fenler veya malzemelerden \u00fcretilmektedir. <\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-greenshift-blocks-accordionitem gs-accordion-item gspb_accordionitem-gsbp-b367761 gsclose\" id=\"gspb_accordionitem-gsbp-b367761\" itemscope><div id=\"gs-trigger-gsbp-af50371-2\" class=\"gs-accordion-item__title\" aria-expanded=\"false\" role=\"button\" tabindex=\"0\" aria-controls=\"gspb-accordion-item-content-gsbp-b367761\"><div class=\"gs-accordion-item__heading\"><strong>Barbek\u00fc k\u00f6m\u00fcr\u00fcn\u00fcz\u00fc farkl\u0131 k\u0131lan nedir?<\/strong><\/div><meta itemprop=\"name\" content=\"<strong&gt;What makes your BBQ charcoal different?<\/strong&gt;\"\/><span class=\"iconfortoggle\"><span class=\"gs-iconbefore\"><\/span><span class=\"gs-iconafter\"><\/span><\/span><\/div><div aria-labelledby=\"gs-trigger-gsbp-af50371-2\" class=\"gs-accordion-item__content\" itemscope id=\"gspb-accordion-item-content-gsbp-b367761\" aria-hidden=\"true\"><div class=\"gs-accordion-item__text\" itemprop=\"text\">\n<p class=\"has-palette-color-3-color has-text-color has-link-color wp-elements-9a3c998c6bf16a1a0d9cd22070319c7e\">Barbek\u00fc k\u00f6m\u00fcr\u00fcm\u00fcz h\u0131zl\u0131 bir \u015fekilde tutu\u015fur, uzun s\u00fcre yanar ve e\u015fit pi\u015firme i\u00e7in s\u00fcrekli \u0131s\u0131 sa\u011flar. %100 do\u011fal sert a\u011fa\u00e7tan yap\u0131lm\u0131\u015f olup, kimyasal i\u00e7ermez ve lezzeti art\u0131r\u0131r. <\/p>\n<\/div><\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-greenshift-blocks-row-column gspb_row__col--6 gspb_row__col--md-12 gspb_row__col--xs-12 gspb_col-id-gsbp-a97b416\" id=\"gspb_col-id-gsbp-a97b416\">\n<div class=\"wp-block-greenshift-blocks-accordion gs-accordion gspb_accordion-id-gsbp-069b82d\" id=\"gspb_accordion-id-gsbp-069b82d\" >\n<div class=\"wp-block-greenshift-blocks-accordionitem gs-accordion-item gspb_accordionitem-gsbp-f232a62 gsclose\" id=\"gspb_accordionitem-gsbp-f232a62\" itemscope><div id=\"gs-trigger-gsbp-069b82d-0\" class=\"gs-accordion-item__title\" aria-expanded=\"false\" role=\"button\" tabindex=\"0\" aria-controls=\"gspb-accordion-item-content-gsbp-f232a62\"><div class=\"gs-accordion-item__heading\"><strong>Nargile k\u00f6m\u00fcr\u00fcn\u00fcz ne kadar s\u00fcre dayan\u0131r?<\/strong><\/div><meta itemprop=\"name\" content=\"<strong&gt;How long does your hookah charcoal last?<\/strong&gt;\"\/><span class=\"iconfortoggle\"><span class=\"gs-iconbefore\"><\/span><span class=\"gs-iconafter\"><\/span><\/span><\/div><div aria-labelledby=\"gs-trigger-gsbp-069b82d-0\" class=\"gs-accordion-item__content\" itemscope id=\"gspb-accordion-item-content-gsbp-f232a62\" aria-hidden=\"true\"><div class=\"gs-accordion-item__text\" itemprop=\"text\">\n<p class=\"has-palette-color-3-color has-text-color has-link-color wp-elements-62a3d1bac9452f58ff8a7ee6f63e403a\">Nargile k\u00f6m\u00fcr\u00fcm\u00fcz, uzun s\u00fcreli seanslar i\u00e7in tasarlanm\u0131\u015f olup, d\u00fczg\u00fcn ve temiz bir \u015fekilde yanar. Tek bir k\u00f6m\u00fcr par\u00e7as\u0131, 90 dakikaya kadar dayanabilir ve kesintisiz, p\u00fcr\u00fczs\u00fcz bir deneyim sunar. <\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-greenshift-blocks-accordionitem gs-accordion-item gspb_accordionitem-gsbp-af317bf gsclose\" id=\"gspb_accordionitem-gsbp-af317bf\" itemscope><div id=\"gs-trigger-gsbp-069b82d-1\" class=\"gs-accordion-item__title\" aria-expanded=\"false\" role=\"button\" tabindex=\"0\" aria-controls=\"gspb-accordion-item-content-gsbp-af317bf\"><div class=\"gs-accordion-item__heading\"><strong>\u00dcr\u00fcnlerinizde herhangi bir katk\u0131 maddesi veya kimyasal madde var m\u0131?<\/strong><\/div><meta itemprop=\"name\" content=\"<strong&gt;Do your products have any additives or chemicals?<\/strong&gt;\"\/><span class=\"iconfortoggle\"><span class=\"gs-iconbefore\"><\/span><span class=\"gs-iconafter\"><\/span><\/span><\/div><div aria-labelledby=\"gs-trigger-gsbp-069b82d-1\" class=\"gs-accordion-item__content\" itemscope id=\"gspb-accordion-item-content-gsbp-af317bf\" aria-hidden=\"true\"><div class=\"gs-accordion-item__text\" itemprop=\"text\">\n<p class=\"has-palette-color-3-color has-text-color has-link-color wp-elements-c4586d562d30787ad80546d16e3a196b\">Hay\u0131r, \u00fcr\u00fcnlerimiz %100 do\u011fal olup zararl\u0131 kimyasallar ve katk\u0131 maddeleri i\u00e7ermez. Hem g\u00fcbrelerimiz hem de k\u00f6m\u00fcrlerimiz g\u00fcvenli, s\u00fcrd\u00fcr\u00fclebilir ve etkili olacak \u015fekilde tasarlanm\u0131\u015ft\u0131r. <\/p>\n<\/div><\/div><\/div>\n<\/div>\n<\/div>\n <\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_gspb_post_css":"@import url(https:\/\/fonts.googleapis.com\/css?family=Poppins|Poppins|Poppins|Poppins|Poppins|Poppins|Poppins|Poppins);#gspb_row-id-gsbp-df20712{justify-content:space-between;margin-top:0;margin-bottom:0;display:flex;flex-wrap:wrap;min-height:500px}#gspb_row-id-gsbp-df20712>.gspb_row__content{display:flex;margin:0 auto;width:100%;flex-wrap:wrap;align-items:center;justify-content:center}div[id^=gspb_col-id]{box-sizing:border-box;position:relative;padding:15px min(3vw,20px)}@media (max-width:991.98px){#gspb_row-id-gsbp-df20712{min-height:500}}body.gspb-bodyfront #gspb_row-id-gsbp-df20712>.gspb_row__content{width:var(--theme-container-width, 1200px);max-width:var(--theme-normal-container-max-width, 1200px)}#gspb_row-id-gsbp-df20712{align-content:center;background-size:cover;background-repeat:no-repeat}@media (max-width:575.98px){#gspb_row-id-gsbp-df20712{background-size:cover;background-repeat:no-repeat}}#gspb_row-id-gsbp-df20712{background-image:url(https:\/\/charcoals.ae\/wp-content\/uploads\/2024\/10\/hero-image-4.jpg);isolation:isolate}#gspb_row-id-gsbp-df20712:hover{background-size:cover}@media (max-width:575.98px){#gspb_row-id-gsbp-df20712:hover{background-size:cover}}#gspb_row-id-gsbp-df20712>.gspb_backgroundOverlay{position:absolute;top:0;left:0;width:100%;height:100%;z-index:-1;background-color:#00000070}#gspb_col-id-gsbp-5341515.gspb_row__col--12{width:100%}@media (max-width:575.98px){#gspb_col-id-gsbp-5341515.gspb_row__col--12{width:100%}}body #gspb_col-id-gsbp-5341515.gspb_row__col--12{display:flex;flex-direction:column;justify-content:center;align-content:center;align-items:center}#gspb_heading-id-gsbp-76e138e{font-size:3rem}@media (max-width:991.98px){#gspb_heading-id-gsbp-76e138e{font-size:2rem}}@media (max-width:575.98px){#gspb_heading-id-gsbp-76e138e{font-size:2rem}}#gspb_heading-id-gsbp-76e138e,#gspb_heading-id-gsbp-76e138e .gsap-g-line{text-align:center!important}#gspb_heading-id-gsbp-76e138e,.gspb_text-id-gsbp-72ef05c{color:var(--wp--preset--color--palette-color-8, var(--theme-palette-color-8, #ffffff))}#gspb_heading-id-gsbp-76e138e{margin-top:0;margin-bottom:0;max-width:800px}.gspb_text-id-gsbp-72ef05c{font-weight:400;font-family:Poppins,sans-serif;font-size:1rem;margin-top:12px!important;margin-bottom:0!important}.gspb_text-id-gsbp-72ef05c,.gspb_text-id-gsbp-72ef05c .gsap-g-line{text-align:center!important}#gspb_row-id-gsbp-fbdca79{justify-content:space-between;display:flex;flex-wrap:wrap;margin-top:130px;margin-bottom:130px}#gspb_row-id-gsbp-fbdca79>.gspb_row__content{display:flex;justify-content:space-between;margin:0 auto;width:100%;flex-wrap:wrap}@media (max-width:991.98px){#gspb_row-id-gsbp-fbdca79{margin-top:80px;margin-bottom:80px}}@media (max-width:575.98px){#gspb_row-id-gsbp-fbdca79{margin-top:30px;margin-bottom:30px}}#gspb_col-id-gsbp-f2c161c.gspb_row__col--6{width:50%}@media (max-width:991.98px){#gspb_col-id-gsbp-f2c161c.gspb_row__col--6{width:100%}}@media (max-width:575.98px){#gspb_col-id-gsbp-f2c161c.gspb_row__col--6{width:100%}}.gspb_row #gspb_col-id-gsbp-f2c161c.gspb_row__col--6{padding:100px 90px}@media (max-width:991.98px){.gspb_row #gspb_col-id-gsbp-f2c161c.gspb_row__col--6{padding-right:100px;padding-left:100px}}@media (max-width:575.98px){.gspb_row #gspb_col-id-gsbp-f2c161c.gspb_row__col--6{padding-right:10px;padding-bottom:100px;padding-left:10px}}#gspb_col-id-gsbp-f2c161c.gspb_row__col--6{background-size:cover;background-repeat:no-repeat}@media (max-width:991.98px){#gspb_col-id-gsbp-f2c161c.gspb_row__col--6{background-position:42% 56%}}#gspb_col-id-gsbp-f2c161c.gspb_row__col--6{background-image:url(https:\/\/charcoals.ae\/wp-content\/uploads\/2024\/10\/contact-image-1.jpg);isolation:isolate}#gspb_col-id-gsbp-f2c161c.gspb_row__col--6:hover{background-size:cover}#gspb_col-id-gsbp-f2c161c.gspb_row__col--6>.gspb_backgroundOverlay{position:absolute;top:0;left:0;width:100%;height:100%;z-index:-1;background-color:#0000004a}#gspb_row-id-gsbp-7313fdb{justify-content:space-between;display:flex;flex-wrap:wrap;align-content:flex-start;margin-top:0;margin-bottom:30px}#gspb_row-id-gsbp-7313fdb>.gspb_row__content{display:flex;justify-content:space-between;margin:0 auto;width:100%;flex-wrap:wrap;align-items:flex-start}body.gspb-bodyfront #gspb_row-id-gsbp-7313fdb>.gspb_row__content,body.gspb-bodyfront #gspb_row-id-gsbp-fbdca79>.gspb_row__content{width:var(--theme-container-width, 1200px);max-width:var(--theme-normal-container-max-width, 1200px)}#gspb_col-id-gsbp-272c810.gspb_row__col--6{width:50%}@media (max-width:575.98px){#gspb_col-id-gsbp-272c810.gspb_row__col--6{width:100%}}@media (min-width:992px){body.gspb-bodyfront #gspb_col-id-gsbp-272c810.gspb_row__col--6{width:calc(22.29% - 0px - 0px)}}@media (min-width:576px) and (max-width:991.98px){body.gspb-bodyfront #gspb_col-id-gsbp-272c810.gspb_row__col--6{width:calc(20% - 0px - 0px)}}#gspb_image-id-gsbp-2bfe568 img{object-position:49% 47%;vertical-align:top;display:inline-block;box-sizing:border-box;max-width:100%;width:custom}#gspb_image-id-gsbp-2bfe568{margin-bottom:0;height:auto}@media (max-width:575.98px){#gspb_image-id-gsbp-2bfe568 img{width:50px}}#gspb_image-id-gsbp-2bfe568 img{height:auto}@media (max-width:991.98px){#gspb_image-id-gsbp-2bfe568,#gspb_image-id-gsbp-2bfe568 img{height:auto}}@media (max-width:767.98px){#gspb_image-id-gsbp-2bfe568,#gspb_image-id-gsbp-2bfe568 img{height:auto}}@media (max-width:575.98px){#gspb_image-id-gsbp-2bfe568,#gspb_image-id-gsbp-2bfe568 img{height:auto}}#gspb_col-id-gsbp-2047624.gspb_row__col--6{width:50%}@media (max-width:575.98px){#gspb_col-id-gsbp-2047624.gspb_row__col--6{width:100%}}@media (min-width:992px){body.gspb-bodyfront #gspb_col-id-gsbp-2047624.gspb_row__col--6{width:calc(77.7% - 0px - 0px)}}@media (min-width:576px) and (max-width:991.98px){body.gspb-bodyfront #gspb_col-id-gsbp-2047624.gspb_row__col--6{width:calc(80% - 0px - 0px)}}#gspb_heading-id-gsbp-29e9c67,.gspb_text-id-gsbp-692c534{color:var(--wp--preset--color--palette-color-8, var(--theme-palette-color-8, #ffffff))}#gspb_heading-id-gsbp-29e9c67{margin-top:0;margin-bottom:15px}@media (max-width:991.98px){#gspb_heading-id-gsbp-29e9c67{margin-bottom:18px}}.gspb_text-id-gsbp-692c534{font-weight:400;font-family:Poppins,sans-serif;font-size:1rem;margin-bottom:16px!important}@media (max-width:991.98px){.gspb_text-id-gsbp-692c534{margin-top:0!important}}#gspb_row-id-gsbp-f34f773{justify-content:space-between;display:flex;flex-wrap:wrap;align-content:flex-start;margin-top:0;margin-bottom:30px}#gspb_row-id-gsbp-f34f773>.gspb_row__content{display:flex;justify-content:space-between;margin:0 auto;width:100%;flex-wrap:wrap;align-items:flex-start}body.gspb-bodyfront #gspb_row-id-gsbp-f34f773>.gspb_row__content{width:var(--theme-container-width, 1200px);max-width:var(--theme-normal-container-max-width, 1200px)}#gspb_col-id-gsbp-aa0d36a.gspb_row__col--6{width:50%}@media (max-width:575.98px){#gspb_col-id-gsbp-aa0d36a.gspb_row__col--6{width:100%}}@media (min-width:992px){body.gspb-bodyfront #gspb_col-id-gsbp-aa0d36a.gspb_row__col--6{width:calc(22.29% - 0px - 0px)}}@media (min-width:576px) and (max-width:991.98px){body.gspb-bodyfront #gspb_col-id-gsbp-aa0d36a.gspb_row__col--6{width:calc(20% - 0px - 0px)}}#gspb_image-id-gsbp-a27dbf3 img{vertical-align:top;display:inline-block;box-sizing:border-box;max-width:100%;height:auto}@media (max-width:991.98px){#gspb_image-id-gsbp-a27dbf3 img{width:custom}}@media (max-width:575.98px){#gspb_image-id-gsbp-a27dbf3 img{width:50px}}@media (max-width:991.98px){#gspb_image-id-gsbp-a27dbf3,#gspb_image-id-gsbp-a27dbf3 img{height:auto}}@media (max-width:767.98px){#gspb_image-id-gsbp-a27dbf3,#gspb_image-id-gsbp-a27dbf3 img{height:auto}}@media (max-width:575.98px){#gspb_image-id-gsbp-a27dbf3,#gspb_image-id-gsbp-a27dbf3 img{height:auto}}#gspb_col-id-gsbp-78de9ff.gspb_row__col--6{width:50%}@media (max-width:575.98px){#gspb_col-id-gsbp-78de9ff.gspb_row__col--6{width:100%}}@media (min-width:992px){body.gspb-bodyfront #gspb_col-id-gsbp-78de9ff.gspb_row__col--6{width:calc(77.7% - 0px - 0px)}}@media (min-width:576px) and (max-width:991.98px){body.gspb-bodyfront #gspb_col-id-gsbp-78de9ff.gspb_row__col--6{width:calc(80% - 0px - 0px)}}#gspb_heading-id-gsbp-632c3e5,.gspb_text-id-gsbp-5446d73{color:var(--wp--preset--color--palette-color-8, var(--theme-palette-color-8, #ffffff))}#gspb_heading-id-gsbp-632c3e5{margin-top:0;margin-bottom:15px}@media (max-width:991.98px){#gspb_heading-id-gsbp-632c3e5{margin-bottom:18px}}.gspb_text-id-gsbp-5446d73{font-weight:400;font-family:Poppins,sans-serif;font-size:1rem;margin-bottom:0!important}@media (max-width:991.98px){.gspb_text-id-gsbp-5446d73{margin-top:0!important}}.gspb_text-id-gsbp-d900805{font-weight:400;font-family:Poppins,sans-serif;font-size:1rem;color:var(--wp--preset--color--palette-color-8, var(--theme-palette-color-8, #ffffff));margin-bottom:16px!important}@media (max-width:991.98px){.gspb_text-id-gsbp-d900805{margin-top:0!important}}#gspb_row-id-gsbp-cc0f9d0{justify-content:space-between;display:flex;flex-wrap:wrap;align-content:flex-start;margin-top:0;margin-bottom:30px}#gspb_row-id-gsbp-cc0f9d0>.gspb_row__content{display:flex;justify-content:space-between;margin:0 auto;width:100%;flex-wrap:wrap;align-items:flex-start}body.gspb-bodyfront #gspb_row-id-gsbp-cc0f9d0>.gspb_row__content{width:var(--theme-container-width, 1200px);max-width:var(--theme-normal-container-max-width, 1200px)}#gspb_col-id-gsbp-928acbf.gspb_row__col--6{width:50%}@media (max-width:575.98px){#gspb_col-id-gsbp-928acbf.gspb_row__col--6{width:100%}}@media (min-width:992px){body.gspb-bodyfront #gspb_col-id-gsbp-928acbf.gspb_row__col--6{width:calc(22.29% - 0px - 0px)}}@media (min-width:576px) and (max-width:991.98px){body.gspb-bodyfront #gspb_col-id-gsbp-928acbf.gspb_row__col--6{width:calc(20% - 0px - 0px)}}#gspb_image-id-gsbp-e1a6522 img{vertical-align:top;display:inline-block;box-sizing:border-box;max-width:100%;height:auto}@media (max-width:575.98px){#gspb_image-id-gsbp-e1a6522{margin-bottom:0}}@media (max-width:991.98px){#gspb_image-id-gsbp-e1a6522 img{width:custom}}@media (max-width:575.98px){#gspb_image-id-gsbp-e1a6522 img{width:50px}}@media (max-width:991.98px){#gspb_image-id-gsbp-e1a6522,#gspb_image-id-gsbp-e1a6522 img{height:auto}}@media (max-width:767.98px){#gspb_image-id-gsbp-e1a6522,#gspb_image-id-gsbp-e1a6522 img{height:auto}}@media (max-width:575.98px){#gspb_image-id-gsbp-e1a6522,#gspb_image-id-gsbp-e1a6522 img{height:auto}}#gspb_col-id-gsbp-83bb57e.gspb_row__col--6{width:50%}@media (max-width:575.98px){#gspb_col-id-gsbp-83bb57e.gspb_row__col--6{width:100%}}@media (min-width:992px){body.gspb-bodyfront #gspb_col-id-gsbp-83bb57e.gspb_row__col--6{width:calc(77.7% - 0px - 0px)}}@media (min-width:576px) and (max-width:991.98px){body.gspb-bodyfront #gspb_col-id-gsbp-83bb57e.gspb_row__col--6{width:calc(80% - 0px - 0px)}}#gspb_heading-id-gsbp-9d40c38{color:var(--wp--preset--color--palette-color-8, var(--theme-palette-color-8, #ffffff));margin-top:0;margin-bottom:15px}@media (max-width:991.98px){#gspb_heading-id-gsbp-9d40c38{margin-bottom:18px}}.gspb_text-id-gsbp-a61e76b{font-weight:400;font-family:Poppins,sans-serif;font-size:1rem;text-decoration:none;margin-bottom:16px!important}.gspb_text-id-gsbp-a61e76b a{text-decoration:none}#gspb_heading-id-gsbp-8f74937,.gspb_text-id-gsbp-a61e76b,.gspb_text-id-gsbp-a61e76b .wp-block a,.gspb_text-id-gsbp-a61e76b .wp-block a:hover,.gspb_text-id-gsbp-a61e76b a,.gspb_text-id-gsbp-a61e76b a:hover,.gspb_text-id-gsbp-a61e76b:hover{color:var(--wp--preset--color--palette-color-8, var(--theme-palette-color-8, #ffffff))}@media (max-width:991.98px){.gspb_text-id-gsbp-a61e76b{margin-top:0!important}}#gspb_col-id-gsbp-048e4e0.gspb_row__col--6{width:50%}@media (max-width:991.98px){#gspb_col-id-gsbp-048e4e0.gspb_row__col--6{width:100%}}@media (max-width:575.98px){#gspb_col-id-gsbp-048e4e0.gspb_row__col--6{width:100%}}.gspb_row #gspb_col-id-gsbp-048e4e0.gspb_row__col--6{padding:100px 90px}@media (max-width:575.98px){.gspb_row #gspb_col-id-gsbp-048e4e0.gspb_row__col--6{padding-right:20px;padding-left:20px}}#gspb_col-id-gsbp-048e4e0.gspb_row__col--6{background-color:var(--wp--preset--color--palette-color-4, var(--theme-palette-color-4, #2C1E18))}#gspb_heading-id-gsbp-8f74937{margin-top:0;margin-bottom:16px}.gspb_text-id-gsbp-6106b59,.gspb_text-id-gsbp-c280505{font-weight:400;font-family:Poppins,sans-serif;margin-bottom:16px!important}.gspb_text-id-gsbp-6106b59{color:var(--wp--preset--color--palette-color-8, var(--theme-palette-color-8, #ffffff));margin-top:0!important}#gspb_row-id-gsbp-15caefc{justify-content:space-between;margin-top:0;display:flex;flex-wrap:wrap;margin-bottom:130px}#gspb_row-id-gsbp-15caefc>.gspb_row__content{display:flex;justify-content:space-between;margin:0 auto;width:100%;flex-wrap:wrap}body.gspb-bodyfront #gspb_row-id-gsbp-15caefc>.gspb_row__content{width:var(--theme-container-width, 1200px);max-width:var(--theme-normal-container-max-width, 1200px)}@media (max-width:991.98px){#gspb_row-id-gsbp-15caefc{margin-bottom:80px}}@media (max-width:575.98px){#gspb_row-id-gsbp-15caefc{margin-bottom:30px}}#gspb_col-id-gsbp-63e0ec3.gspb_row__col--8{width:66.66666666666667%}@media (max-width:575.98px){#gspb_col-id-gsbp-63e0ec3.gspb_row__col--8{width:100%}}@media (min-width:992px){body.gspb-bodyfront #gspb_col-id-gsbp-63e0ec3.gspb_row__col--8{width:calc(60.76% - 0px - 0px)}}.gspb_row #gspb_col-id-gsbp-63e0ec3.gspb_row__col--8{padding:100px}@media (max-width:575.98px){.gspb_row #gspb_col-id-gsbp-63e0ec3.gspb_row__col--8{padding:50px 20px}}#gspb_col-id-gsbp-63e0ec3.gspb_row__col--8{background-color:var(--wp--preset--color--palette-color-8, var(--theme-palette-color-8, #ffffff))}#gspb_heading-id-gsbp-0903a06{color:var(--wp--preset--color--palette-color-1, var(--theme-palette-color-1, #CB602C));margin-top:0;margin-bottom:34px}@media (max-width:991.98px){#gspb_heading-id-gsbp-0903a06{margin-bottom:18px}}.gspb_text-id-gsbp-c280505{font-size:1rem;color:var(--wp--preset--color--palette-color-4, var(--theme-palette-color-4, #2C1E18))}@media (max-width:991.98px){.gspb_text-id-gsbp-c280505{margin-top:0!important}}@media (max-width:575.98px){.gspb_text-id-gsbp-c280505{margin-top:0!important}}#gspb_col-id-gsbp-e0439e7.gspb_row__col--4{width:33.333333333333336%}@media (max-width:575.98px){#gspb_col-id-gsbp-e0439e7.gspb_row__col--4{width:100%}}@media (min-width:992px){body.gspb-bodyfront #gspb_col-id-gsbp-e0439e7.gspb_row__col--4{width:calc(39.23% - 0px - 0px)}}.gspb_row #gspb_col-id-gsbp-e0439e7.gspb_row__col--4{padding:0}#gspb_row-id-gsbp-6af23b1{justify-content:space-between;margin-top:0;display:flex;flex-wrap:wrap;align-content:flex-start;margin-bottom:0;padding-top:100px;padding-bottom:100px}#gspb_row-id-gsbp-6af23b1>.gspb_row__content{display:flex;margin:0 auto;width:100%;flex-wrap:wrap;align-items:flex-start;justify-content:center}.gspb_row{position:relative}body.gspb-bodyfront #gspb_row-id-gsbp-6af23b1>.gspb_row__content{width:var(--theme-container-width, 1200px);max-width:var(--theme-normal-container-max-width, 1200px)}@media (max-width:991.98px){#gspb_row-id-gsbp-6af23b1{margin-bottom:0}}@media (max-width:575.98px){#gspb_row-id-gsbp-6af23b1{margin-bottom:0}}#gspb_row-id-gsbp-6af23b1{background-size:cover;background-repeat:no-repeat}@media (max-width:991.98px){#gspb_row-id-gsbp-6af23b1{background-size:cover;background-repeat:no-repeat}}#gspb_row-id-gsbp-6af23b1{background-image:url(https:\/\/charcoals.ae\/wp-content\/uploads\/2024\/10\/image-cta-2.jpg);isolation:isolate}#gspb_row-id-gsbp-6af23b1:hover{background-size:cover}@media (max-width:991.98px){#gspb_row-id-gsbp-6af23b1:hover{background-size:cover}}#gspb_row-id-gsbp-6af23b1>.gspb_backgroundOverlay{position:absolute;top:0;left:0;width:100%;height:100%;z-index:-1;background-color:#000000a6}#gspb_col-id-gsbp-8b2cd7c.gspb_row__col--6{width:50%}@media (max-width:991.98px){#gspb_col-id-gsbp-8b2cd7c.gspb_row__col--6{width:100%}}@media (max-width:575.98px){#gspb_col-id-gsbp-8b2cd7c.gspb_row__col--6{width:100%}}@media (min-width:992px){body.gspb-bodyfront #gspb_col-id-gsbp-8b2cd7c.gspb_row__col--6{width:calc(100% - 0px - 0px)}}@media (max-width:575.98px){body.gspb-bodyfront #gspb_col-id-gsbp-8b2cd7c.gspb_row__col--6{width:calc(100% - 0px - 0px)}}body #gspb_col-id-gsbp-8b2cd7c.gspb_row__col--6{display:flex;flex-direction:column;justify-content:center;align-items:flex-start}#gspb_heading-id-gsbp-c32886f,.gspb_text-id-gsbp-3a84d44{color:var(--wp--preset--color--palette-color-8, var(--theme-palette-color-8, #ffffff));margin-top:0;margin-bottom:16px}.gspb_text-id-gsbp-3a84d44{font-weight:400;font-family:Poppins,sans-serif;margin-top:0!important;margin-bottom:20px!important}@media (max-width:991.98px){.gspb_text-id-gsbp-3a84d44{margin-top:0!important}}#gspb_col-id-gsbp-dd5b85c.gspb_row__col--6{width:50%}@media (max-width:991.98px){#gspb_col-id-gsbp-dd5b85c.gspb_row__col--6{width:100%}}@media (max-width:575.98px){#gspb_col-id-gsbp-dd5b85c.gspb_row__col--6{width:100%}body.gspb-bodyfront #gspb_col-id-gsbp-dd5b85c.gspb_row__col--6{width:calc(100% - 0px - 0px)}}@media (max-width:991.98px){.gspb_row #gspb_col-id-gsbp-dd5b85c.gspb_row__col--6{padding-bottom:0}}body #gspb_col-id-gsbp-a97b416.gspb_row__col--6,body #gspb_col-id-gsbp-dd5b85c.gspb_row__col--6{display:flex;flex-direction:column;justify-content:flex-start;align-items:stretch}#gspb_accordion-id-gsbp-af50371 .gs-accordion-item.gsclose>.gs-accordion-item__content{overflow:hidden;opacity:0}#gspb_accordion-id-gsbp-af50371 .gs-accordion-item.gsopen>.gs-accordion-item__content{opacity:1;max-height:5000px}#gspb_accordion-id-gsbp-af50371 .gs-accordion-item>.gs-accordion-item__title>.gs-accordion-item__heading{outline:0;text-decoration:none;margin:0!important;padding:0!important;flex-grow:1}#gspb_accordion-id-gsbp-af50371 .gs-accordion-item>.gs-accordion-item__title{z-index:1;margin:0;cursor:pointer;transition:all .3s ease-in-out;position:relative;display:flex;justify-content:space-between;align-items:center;flex-wrap:nowrap}#gspb_accordion-id-gsbp-af50371 .gs-accordion-item>.gs-accordion-item__content{z-index:0;position:relative;max-height:0;will-change:max-height;transition:all .25s ease-out}#gspb_accordion-id-gsbp-af50371 .gs-accordion-item>.gs-accordion-item__title{background-color:#f9f9f9;border-style:solid;border-width:1px;border-color:#00000012}#gspb_accordion-id-gsbp-af50371 .gs-accordion-item>.gs-accordion-item__content{background-color:#fff;border-style:solid;border-width:1px;border-color:#00000000 #00000012 #00000012}#gspb_accordion-id-gsbp-af50371 .gs-accordion-item{margin-bottom:10px}#gspb_accordion-id-gsbp-af50371 .gs-accordion-item>.gs-accordion-item__content>.gs-accordion-item__text,#gspb_accordion-id-gsbp-af50371 .gs-accordion-item>.gs-accordion-item__title{padding:15px 20px}.gs-accordion .gs-accordion-item.gsopen .gs-accordion-item__title .gs-iconafter{transform:rotate(0)}body #gspb_accordionitem-gsbp-e8bb661.gs-accordion-item .gs-accordion-item__title{background-color:var(--wp--preset--color--palette-color-5, var(--theme-palette-color-5, #F2EFE7))}#gspb_accordionitem-gsbp-e8bb661 .gs-accordion-item__title>*{color:var(--wp--preset--color--palette-color-1, var(--theme-palette-color-1, #CB602C))!important}#gspb_accordionitem-gsbp-e8bb661 span.iconfortoggle .gs-iconafter,#gspb_accordionitem-gsbp-e8bb661 span.iconfortoggle .gs-iconbefore{background-color:var(--wp--preset--color--palette-color-1, var(--theme-palette-color-1, #CB602C))!important}#gspb_accordionitem-gsbp-e8bb661 .gs-accordion-item__title{border-color:var(--wp--preset--color--palette-color-5, var(--theme-palette-color-5, #F2EFE7))!important}body #gspb_accordionitem-gsbp-f27e73d.gs-accordion-item .gs-accordion-item__title{background-color:var(--wp--preset--color--palette-color-5, var(--theme-palette-color-5, #F2EFE7))}#gspb_accordionitem-gsbp-f27e73d .gs-accordion-item__title>*{color:var(--wp--preset--color--palette-color-1, var(--theme-palette-color-1, #CB602C))!important}#gspb_accordionitem-gsbp-f27e73d span.iconfortoggle .gs-iconafter,#gspb_accordionitem-gsbp-f27e73d span.iconfortoggle .gs-iconbefore{background-color:var(--wp--preset--color--palette-color-1, var(--theme-palette-color-1, #CB602C))!important}#gspb_accordionitem-gsbp-f27e73d .gs-accordion-item__title{border-color:var(--wp--preset--color--palette-color-5, var(--theme-palette-color-5, #F2EFE7))!important}body #gspb_accordionitem-gsbp-b367761.gs-accordion-item .gs-accordion-item__title{background-color:var(--wp--preset--color--palette-color-5, var(--theme-palette-color-5, #F2EFE7))}#gspb_accordionitem-gsbp-b367761 .gs-accordion-item__title>*{color:var(--wp--preset--color--palette-color-1, var(--theme-palette-color-1, #CB602C))!important}#gspb_accordionitem-gsbp-b367761 span.iconfortoggle .gs-iconafter,#gspb_accordionitem-gsbp-b367761 span.iconfortoggle .gs-iconbefore{background-color:var(--wp--preset--color--palette-color-1, var(--theme-palette-color-1, #CB602C))!important}#gspb_accordionitem-gsbp-b367761 .gs-accordion-item__title{border-color:var(--wp--preset--color--palette-color-5, var(--theme-palette-color-5, #F2EFE7))!important}#gspb_col-id-gsbp-a97b416.gspb_row__col--6{width:50%}@media (max-width:991.98px){#gspb_col-id-gsbp-a97b416.gspb_row__col--6{width:100%}}@media (max-width:575.98px){#gspb_col-id-gsbp-a97b416.gspb_row__col--6{width:100%}body.gspb-bodyfront #gspb_col-id-gsbp-a97b416.gspb_row__col--6{width:calc(100% - 0px - 0px)}}@media (max-width:991.98px){.gspb_row #gspb_col-id-gsbp-a97b416.gspb_row__col--6{padding-top:0}}#gspb_accordion-id-gsbp-069b82d .gs-accordion-item.gsclose>.gs-accordion-item__content{overflow:hidden;opacity:0}#gspb_accordion-id-gsbp-069b82d .gs-accordion-item.gsopen>.gs-accordion-item__content{opacity:1;max-height:5000px}#gspb_accordion-id-gsbp-069b82d .gs-accordion-item>.gs-accordion-item__title>.gs-accordion-item__heading{outline:0;text-decoration:none;margin:0!important;padding:0!important;flex-grow:1}#gspb_accordion-id-gsbp-069b82d .gs-accordion-item>.gs-accordion-item__title{z-index:1;margin:0;cursor:pointer;transition:all .3s ease-in-out;position:relative;display:flex;justify-content:space-between;align-items:center;flex-wrap:nowrap}#gspb_accordion-id-gsbp-069b82d .gs-accordion-item>.gs-accordion-item__content{z-index:0;position:relative;max-height:0;will-change:max-height;transition:all .25s ease-out}#gspb_accordion-id-gsbp-069b82d .gs-accordion-item>.gs-accordion-item__title{background-color:#f9f9f9;border-style:solid;border-width:1px;border-color:#00000012}#gspb_accordion-id-gsbp-069b82d .gs-accordion-item>.gs-accordion-item__content{background-color:#fff;border-style:solid;border-width:1px;border-color:#00000000 #00000012 #00000012}#gspb_accordion-id-gsbp-069b82d .gs-accordion-item>.gs-accordion-item__title span.iconfortoggle,#gspb_accordion-id-gsbp-af50371 .gs-accordion-item>.gs-accordion-item__title span.iconfortoggle{margin-left:15px;display:inline-block;height:14px;width:14px;position:relative}#gspb_accordion-id-gsbp-069b82d .gs-accordion-item{margin-bottom:10px}#gspb_accordion-id-gsbp-069b82d .gs-accordion-item>.gs-accordion-item__content>.gs-accordion-item__text,#gspb_accordion-id-gsbp-069b82d .gs-accordion-item>.gs-accordion-item__title{padding:15px 20px}.gs-accordion .gs-accordion-item__title span.iconfortoggle .gs-iconafter,.gs-accordion .gs-accordion-item__title span.iconfortoggle .gs-iconbefore{content:'';width:14px;height:2px;border-radius:2px;background-color:#111;position:absolute;top:6px;left:0}.gs-accordion .gs-accordion-item__title span.iconfortoggle .gs-iconafter{transform:rotate(90deg);transition:all .3s ease-in-out}body #gspb_accordionitem-gsbp-f232a62.gs-accordion-item .gs-accordion-item__title{background-color:var(--wp--preset--color--palette-color-5, var(--theme-palette-color-5, #F2EFE7))}#gspb_accordionitem-gsbp-f232a62 .gs-accordion-item__title>*{color:var(--wp--preset--color--palette-color-1, var(--theme-palette-color-1, #CB602C))!important}#gspb_accordionitem-gsbp-f232a62 span.iconfortoggle .gs-iconafter,#gspb_accordionitem-gsbp-f232a62 span.iconfortoggle .gs-iconbefore{background-color:var(--wp--preset--color--palette-color-1, var(--theme-palette-color-1, #CB602C))!important}#gspb_accordionitem-gsbp-f232a62 .gs-accordion-item__title{border-color:var(--wp--preset--color--palette-color-5, var(--theme-palette-color-5, #F2EFE7))!important}body #gspb_accordionitem-gsbp-af317bf.gs-accordion-item .gs-accordion-item__title{background-color:var(--wp--preset--color--palette-color-5, var(--theme-palette-color-5, #F2EFE7))}#gspb_accordionitem-gsbp-af317bf .gs-accordion-item__title>*{color:var(--wp--preset--color--palette-color-1, var(--theme-palette-color-1, #CB602C))!important}#gspb_accordionitem-gsbp-af317bf span.iconfortoggle .gs-iconafter,#gspb_accordionitem-gsbp-af317bf span.iconfortoggle .gs-iconbefore{background-color:var(--wp--preset--color--palette-color-1, var(--theme-palette-color-1, #CB602C))!important}#gspb_accordionitem-gsbp-af317bf .gs-accordion-item__title{border-color:var(--wp--preset--color--palette-color-5, var(--theme-palette-color-5, #F2EFE7))!important}.gspb_id-gsbp-7513ce4{display:flex}.gspb_id-gsbp-7513ce4 .gspb_map-wrapper{width:100%;height:400px;isolation:isolate}","_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","postBodyCss":"","postBodyMargin":[],"postBodyPadding":[],"postBodyBackground":{"backgroundType":"classic","gradient":""},"footnotes":""},"class_list":["post-1477","page","type-page","status-publish","hentry"],"blocksy_meta":[],"taxonomy_info":[],"featured_image_src_large":false,"author_info":{"display_name":"Hassan Rajabian","author_link":"https:\/\/charcoals.ae\/tr\/author\/h-rajabian\/"},"comment_info":0,"_links":{"self":[{"href":"https:\/\/charcoals.ae\/tr\/wp-json\/wp\/v2\/pages\/1477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/charcoals.ae\/tr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/charcoals.ae\/tr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/charcoals.ae\/tr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/charcoals.ae\/tr\/wp-json\/wp\/v2\/comments?post=1477"}],"version-history":[{"count":0,"href":"https:\/\/charcoals.ae\/tr\/wp-json\/wp\/v2\/pages\/1477\/revisions"}],"wp:attachment":[{"href":"https:\/\/charcoals.ae\/tr\/wp-json\/wp\/v2\/media?parent=1477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}